{"id":525,"count":1,"description":"","link":"https:\/\/aboveit.fi\/en\/tag\/training-2\/","name":"training","slug":"training-2","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>training arkistot - Above IT Oy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aboveit.fi\/en\/tag\/training-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"training arkistot - Above IT Oy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aboveit.fi\/en\/tag\/training-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Above IT Oy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/en\\\/tag\\\/training-2\\\/\",\"url\":\"https:\\\/\\\/aboveit.fi\\\/en\\\/tag\\\/training-2\\\/\",\"name\":\"training arkistot - Above IT Oy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/en\\\/tag\\\/training-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/en\\\/tag\\\/training-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/aboveit.fi\\\/en\\\/it-management-resource-partner\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"training\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/aboveit.fi\\\/en\\\/\",\"name\":\"We Are Above IT\",\"description\":\"Tietohallinnon voimavarakumppani\",\"publisher\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aboveit.fi\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/en\\\/#organization\",\"name\":\"Above IT Oy\",\"url\":\"https:\\\/\\\/aboveit.fi\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aboveit.fi\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/aboveIT-logo.png\",\"contentUrl\":\"https:\\\/\\\/aboveit.fi\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/aboveIT-logo.png\",\"width\":1613,\"height\":383,\"caption\":\"Above IT Oy\"},\"image\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aboveitfi\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aboveitfi\",\"https:\\\/\\\/instagram.com\\\/aboveitfi\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"training arkistot - Above IT Oy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aboveit.fi\/en\/tag\/training-2\/","og_locale":"en_US","og_type":"article","og_title":"training arkistot - Above IT Oy","og_url":"https:\/\/aboveit.fi\/en\/tag\/training-2\/","og_site_name":"Above IT Oy","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aboveit.fi\/en\/tag\/training-2\/","url":"https:\/\/aboveit.fi\/en\/tag\/training-2\/","name":"training arkistot - Above IT Oy","isPartOf":{"@id":"https:\/\/aboveit.fi\/en\/#website"},"breadcrumb":{"@id":"https:\/\/aboveit.fi\/en\/tag\/training-2\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/aboveit.fi\/en\/tag\/training-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/aboveit.fi\/en\/it-management-resource-partner\/"},{"@type":"ListItem","position":2,"name":"training"}]},{"@type":"WebSite","@id":"https:\/\/aboveit.fi\/en\/#website","url":"https:\/\/aboveit.fi\/en\/","name":"We Are Above IT","description":"Tietohallinnon voimavarakumppani","publisher":{"@id":"https:\/\/aboveit.fi\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aboveit.fi\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aboveit.fi\/en\/#organization","name":"Above IT Oy","url":"https:\/\/aboveit.fi\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aboveit.fi\/en\/#\/schema\/logo\/image\/","url":"https:\/\/aboveit.fi\/wp-content\/uploads\/2024\/10\/aboveIT-logo.png","contentUrl":"https:\/\/aboveit.fi\/wp-content\/uploads\/2024\/10\/aboveIT-logo.png","width":1613,"height":383,"caption":"Above IT Oy"},"image":{"@id":"https:\/\/aboveit.fi\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aboveitfi","https:\/\/www.linkedin.com\/company\/aboveitfi","https:\/\/instagram.com\/aboveitfi"]}]}},"_links":{"self":[{"href":"https:\/\/aboveit.fi\/en\/wp-json\/wp\/v2\/tags\/525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aboveit.fi\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/aboveit.fi\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/aboveit.fi\/en\/wp-json\/wp\/v2\/posts?tags=525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}