{"id":528,"count":1,"description":"","link":"https:\/\/aboveit.fi\/de\/tag\/simulationen\/","name":"simulationen","slug":"simulationen","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>simulationen arkistot - Above IT Oy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aboveit.fi\/de\/tag\/simulationen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"simulationen arkistot - Above IT Oy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aboveit.fi\/de\/tag\/simulationen\/\" \/>\n<meta property=\"og:site_name\" content=\"Above IT Oy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/tag\\\/simulationen\\\/\",\"url\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/tag\\\/simulationen\\\/\",\"name\":\"simulationen arkistot - Above IT Oy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/tag\\\/simulationen\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/tag\\\/simulationen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/ihr-ressourcenpartner-fuer-die-it-verwaltung\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"simulationen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/\",\"name\":\"We Are Above IT\",\"description\":\"Tietohallinnon voimavarakumppani\",\"publisher\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#organization\",\"name\":\"Above IT Oy\",\"url\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aboveit.fi\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/aboveIT-logo.png\",\"contentUrl\":\"https:\\\/\\\/aboveit.fi\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/aboveIT-logo.png\",\"width\":1613,\"height\":383,\"caption\":\"Above IT Oy\"},\"image\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aboveitfi\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aboveitfi\",\"https:\\\/\\\/instagram.com\\\/aboveitfi\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"simulationen arkistot - Above IT Oy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aboveit.fi\/de\/tag\/simulationen\/","og_locale":"de_DE","og_type":"article","og_title":"simulationen arkistot - Above IT Oy","og_url":"https:\/\/aboveit.fi\/de\/tag\/simulationen\/","og_site_name":"Above IT Oy","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aboveit.fi\/de\/tag\/simulationen\/","url":"https:\/\/aboveit.fi\/de\/tag\/simulationen\/","name":"simulationen arkistot - Above IT Oy","isPartOf":{"@id":"https:\/\/aboveit.fi\/de\/#website"},"breadcrumb":{"@id":"https:\/\/aboveit.fi\/de\/tag\/simulationen\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/aboveit.fi\/de\/tag\/simulationen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/aboveit.fi\/de\/ihr-ressourcenpartner-fuer-die-it-verwaltung\/"},{"@type":"ListItem","position":2,"name":"simulationen"}]},{"@type":"WebSite","@id":"https:\/\/aboveit.fi\/de\/#website","url":"https:\/\/aboveit.fi\/de\/","name":"We Are Above IT","description":"Tietohallinnon voimavarakumppani","publisher":{"@id":"https:\/\/aboveit.fi\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aboveit.fi\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aboveit.fi\/de\/#organization","name":"Above IT Oy","url":"https:\/\/aboveit.fi\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aboveit.fi\/de\/#\/schema\/logo\/image\/","url":"https:\/\/aboveit.fi\/wp-content\/uploads\/2024\/10\/aboveIT-logo.png","contentUrl":"https:\/\/aboveit.fi\/wp-content\/uploads\/2024\/10\/aboveIT-logo.png","width":1613,"height":383,"caption":"Above IT Oy"},"image":{"@id":"https:\/\/aboveit.fi\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aboveitfi","https:\/\/www.linkedin.com\/company\/aboveitfi","https:\/\/instagram.com\/aboveitfi"]}]}},"_links":{"self":[{"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/tags\/528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/posts?tags=528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}