{"id":13155,"date":"2026-09-01T12:04:06","date_gmt":"2026-09-01T09:04:06","guid":{"rendered":"https:\/\/aboveit.fi\/?p=13155"},"modified":"2026-09-01T13:40:45","modified_gmt":"2026-09-01T10:40:45","slug":"das-verwaltungsmodell-halt-azure-im-griff","status":"publish","type":"post","link":"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/","title":{"rendered":"Eine einmal j\u00e4hrlich durchgef\u00fchrte Sicherheitsschulung reicht nicht aus"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"13155\" class=\"elementor elementor-13155 elementor-13154\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d849432 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d849432\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e780006\" data-id=\"e780006\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-235968e elementor-widget elementor-widget-text-editor\" data-id=\"235968e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Mit einer einmal j\u00e4hrlich durchgef\u00fchrten Sicherheitsschulung l\u00e4sst sich weder die Cyber-Kompetenz noch die Resilienz einer Organisation messen oder steigern, und sie \u00e4ndert auch nicht die Arbeitsweise. Sicherheitsschulung sollte vielmehr als kontinuierliches und messbares Handeln in der gesamten Organisation verstanden werden. In diesem Blog gehen wir auf die Auswirkungen von Schulungen auf die Informationssicherheit von Organisationen ein und erkl\u00e4ren, warum wir bei Above IT Moxso als Partner gew\u00e4hlt haben, um die Sicherheitsresilienz unserer Kunden zu erh\u00f6hen.  <\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b131890 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b131890\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5e401a\" data-id=\"b5e401a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd0efa9 elementor-widget elementor-widget-heading\" data-id=\"fd0efa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Angriffe entwickeln sich immer schneller<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41c671c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41c671c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31b2e6cd\" data-id=\"31b2e6cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-403a0dfa elementor-widget elementor-widget-text-editor\" data-id=\"403a0dfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In manchen Organisationen bedeutet Sicherheitsschulung immer noch eines: Im Herbst wird ein einst\u00fcndiges Video angeschaut, die Teilnahme abgehakt und f\u00fcr das Audit vermerkt, dass das Personal geschult wurde. Im M\u00e4rz kommt eine nahezu perfekte Phishing-Nachricht an, jemand meldet sich auf der falschen Seite an und die Zugangsdaten sind beim Angreifer. Das Problem ist nicht, dass es den Menschen egal w\u00e4re. Das Problem ist in erster Linie der Mangel an Schulung sowie unzureichende Prozesse.   <\/p><p>Die leicht erkennbare Phishing-Nachricht mit Rechtschreibfehlern geh\u00f6rt der Vergangenheit an. Heutzutage ist eine finnischsprachige Betrugsnachricht sprachlich so einwandfrei, dass man allein daran nicht direkt erkennen kann, dass es sich um Betrug handelt. <\/p><p>Auch die Kan\u00e4le haben sich ver\u00e4ndert. Ein Angriff beginnt nicht mehr nur per E-Mail. Phishing ist auf die Telefone der Nutzer \u00fcbergegangen, wo m\u00f6glicherweise keine Unternehmensschutzma\u00dfnahmen verf\u00fcgbar sind. CEO-Fraud beginnt mit einer E-Mail und wird per SMS oder Anruf fortgesetzt, um Anfragen zu best\u00e4tigen. Die Kombination funktioniert, weil jedes einzelne Ereignis zus\u00e4tzliche Glaubw\u00fcrdigkeit schafft, wenn das vorherige bereits den Boden bereitet hat.    <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-96413bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96413bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36bfd6c\" data-id=\"36bfd6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a4df8b elementor-widget elementor-widget-heading\" data-id=\"7a4df8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vertrautes, vertrauteres Teams? <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab7e5d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab7e5d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3035440\" data-id=\"3035440\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd3be55 elementor-widget elementor-widget-text-editor\" data-id=\"bd3be55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Externe Teams-Kommunikation ist standardm\u00e4\u00dfig offen. Jeder aus einem anderen M365-Tenant kann einer Person eine Nachricht oder einen Anruf senden. Teams wird mehr vertraut als E-Mail, und das haben auch Angreifer bemerkt. In Schulungen sollten verschiedene Kan\u00e4le ber\u00fccksichtigt werden und nicht nur auf Betrugsversuche per E-Mail fokussiert werden.   <\/p><p>Zu beachten ist auch, dass selbst Schulung allein nicht ausreicht. Technische Schutzma\u00dfnahmen m\u00fcssen parallel entwickelt werden, sowohl bei Teams als auch in anderen Bereichen. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-914c291 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"914c291\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f75a73\" data-id=\"2f75a73\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26d7be6 elementor-widget elementor-widget-heading\" data-id=\"26d7be6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sicherheitsbewusstsein kann und sollte gemessen werden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82a3ae1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82a3ae1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f49419b\" data-id=\"f49419b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-019244e elementor-widget elementor-widget-text-editor\" data-id=\"019244e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Statt f\u00fcr alle dieselbe Schulung anzubieten, beginnt ein funktionierendes Modell mit einer Ausgangsmessung. An die Mitarbeiter der Organisation werden simulierte Phishing-Nachrichten gesendet und beobachtet, was passiert. Wer hat geklickt, wer hat Zugangsdaten eingegeben, wer hat die Nachricht gemeldet usw.  <\/p><p dir=\"ltr\">Aus den Ergebnissen entstehen Risikoprofile auf individueller Ebene. Die Schulung wird entsprechend ausgerichtet. Eine Person mit hohem Risiko erh\u00e4lt intensive, wiederholte \u00dcbungen zur Phishing-Erkennung, und wer die Grundlagen bereits beherrscht, erh\u00e4lt anspruchsvollere Inhalte. Die Entwicklung wird aktiv verfolgt.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb1006e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb1006e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-825e4cf\" data-id=\"825e4cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a304ec elementor-widget elementor-widget-heading\" data-id=\"2a304ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum wir Moxso als Partner gew\u00e4hlt haben<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9fb3a84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9fb3a84\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85fd5f1\" data-id=\"85fd5f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f27ccc elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7f27ccc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p dir=\"ltr\">Wir haben eine Reihe von Sicherheitsschulungsplattformen durchgesehen und uns f\u00fcr das d\u00e4nische Moxso entschieden, weil es unseren Anforderungen am besten entsprach. Ihre Philosophie bei Sicherheitsschulungen traf auf uns zu. Die Plattform kombiniert kontinuierliche Phishing-Simulationen und kurze Schulungseinheiten und erstellt Risikoprofile auf individueller Ebene, die sich entsprechend dem Verhalten aktualisieren.  <\/p><p dir=\"ltr\">Moxso-Vorteile in K\u00fcrze:<\/p><ul dir=\"ltr\"><li><strong>Inhalte sind auf Finnisch und authentisch erstellt. <\/strong>Schulungsvideos wurden mit Schauspielern auch auf Finnisch gedreht. Es handelt sich also nicht um maschinell \u00fcbersetzte Untertitel \u00fcber einem englischsprachigen Video. <\/li><li><strong>Simulationen beschr\u00e4nken sich nicht auf gew\u00f6hnliche E-Mail-Links.<\/strong> Zu den Kampagnentypen geh\u00f6ren verschiedene realistische Betrugsversuche, die sich nicht nur auf E-Mail-Nachrichten oder darin enthaltene Links beschr\u00e4nken.<\/li><li><strong>Datenleck-\u00dcberwachung ist im selben Service enthalten.<\/strong> \u00dcber die Plattform ist ersichtlich, ob die Benutzernamen der Organisation in externen Datenlecks auftauchen.<\/li><li><strong>Schulung ist Microlearning.<\/strong> In kleinen Portionen auf einmal, die nicht zu viel Zeit in Anspruch nehmen.<\/li><li><strong>Gamification ist integriert.<\/strong> Die Plattform erm\u00f6glicht kleine Wettbewerbe. Wer in der Organisation hat die meisten Phishing-Nachrichten erkannt und die meisten Schulungen absolviert. <\/li><li><strong>Melden ist nur einen Klick entfernt.<\/strong> Phishing wird \u00fcber eine Schaltfl\u00e4che in Outlook gemeldet, die f\u00fcr alle leicht zug\u00e4nglich ist. Ebenso erhalten Nutzer sofort eine R\u00fcckmeldung, wenn sie eine Phishing-Nachricht erkennen. So werden IT oder Kollegen nicht unn\u00f6tig mit Meldungen \u00fcber Phishing-Nachrichtensimulationen belastet.  <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b76e3a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b76e3a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11ac872\" data-id=\"11ac872\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3f9e59 elementor-widget elementor-widget-heading\" data-id=\"a3f9e59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NIS2 und das Cybersicherheitsgesetz brachten auch Anforderungen an Schulungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c49fc81 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c49fc81\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c2c8966\" data-id=\"c2c8966\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52d90ca elementor-widget elementor-widget-text-editor\" data-id=\"52d90ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p dir=\"ltr\">Das Cybersicherheitsgesetz trat in Finnland im April 2025 in Kraft und brachte die Anforderungen der NIS2-Richtlinie in die nationale Gesetzgebung ein. F\u00fcr Organisationen im Anwendungsbereich ist die Sicherheitsschulung des Personals nicht mehr nur eine formale Praxis, sondern Teil des erforderlichen Risikomanagements, f\u00fcr das letztendlich die Unternehmensleitung verantwortlich ist. <\/p><p dir=\"ltr\">Die Aufsichtsbeh\u00f6rde k\u00f6nnte folgende Fragen stellen: Ist die Schulung kontinuierlich, ist sie dokumentiert und kannst du die Entwicklung in Zahlen zeigen? Ein einmal j\u00e4hrlich angeschautes Video oder gelesenes Dokument beantwortet keine dieser Fragen. Ein auf Simulationen und Kennzahlen basierendes Programm beantwortet alle drei ohne zus\u00e4tzlichen Berichtsaufwand.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a40486 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a40486\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bafccff\" data-id=\"bafccff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f265f0 elementor-widget elementor-widget-heading\" data-id=\"8f265f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wo sollte man anfangen?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8ed766 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8ed766\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23ad81c\" data-id=\"23ad81c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5a7b36 elementor-widget elementor-widget-text-editor\" data-id=\"f5a7b36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zur Entwicklung des Sicherheitsbewusstseins ist dies ein gutes Vorgehen:<\/p><ol dir=\"ltr\"><li><strong>Miss das Ausgangsniveau.<\/strong> F\u00fchre eine Ausgangsmessung durch, bevor du irgendetwas schulst. Ohne sie kannst du keine Entwicklung nachweisen. <\/li><li><strong>Vereinbare Kennzahlen und Berichterstattung. <\/strong>Entscheide, was und wann an die Gesch\u00e4ftsleitung oder andere in der Organisation berichtet wird. Beispielsweise reicht eine viertelj\u00e4hrliche Zusammenfassung. <\/li><li><strong>Beginne die Schulung mit kurzen Einheiten<\/strong>. Ein langer Pflichtkurs demotiviert und bringt nicht die gew\u00fcnschte Kompetenz. <\/li><li><strong>Mache das Melden einfach und verkn\u00fcpfe es mit bestehenden Sicherheitsprozessen<\/strong>. Meldungen der Nutzer \u00fcber Phishing-Nachrichten sowie andere Sicherheitsvorf\u00e4lle\/-st\u00f6rungen m\u00fcssen irgendwo landen, wo darauf reagiert wird. <\/li><li><strong>Benenne keine Klicker<\/strong>. Wenn die Simulation zur Schande wird, sinken die Melderaten und du verlierst eine deiner wichtigsten Kennzahlen. <\/li><li><strong>Richte Inhalte nach Rollen aus.<\/strong> Beispiele: Finanzen brauchen Rechnungsbetrug, F\u00fchrung braucht gezielte Spionage, Produktion braucht Ger\u00e4te und physische Sicherheit.<\/li><li><strong>F\u00fchre \u00dcbungen \u00fcber E-Mail hinaus<\/strong>. Nimm QR-Kampagnen sp\u00e4testens in der zweiten Runde mit auf. Wenn ihr noch nie etwas anderes als E-Mail-Links getestet habt, habt ihr keinerlei Informationen dar\u00fcber, wie die Organisation auf Betrug reagiert, der auf dem Telefon ankommt.  <\/li><\/ol><p>Sicherheitsbewusstsein ist die einzige Kontrolle, die auch dann funktioniert, wenn der technische Schutz versagt. Deshalb sollte man es mindestens genauso ernst nehmen wie Backups: kontinuierlich, messbar und regelm\u00e4\u00dfig getestet. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94293c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94293c8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bdf1981\" data-id=\"bdf1981\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e908c8 elementor-widget elementor-widget-text-editor\" data-id=\"1e908c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Wir sind <a href=\"https:\/\/moxso.com\/\" target=\"_blank\" rel=\"noopener\">Moxso<\/a>-Partner und bauen gemeinsam mit Kunden ein Sicherheitsschulungsprogramm auf, das eine messbare Ver\u00e4nderung bewirkt und Audits standh\u00e4lt. Wir k\u00fcmmern uns um die Ausgangsmessung, die Implementierung, die rollenspezifische Ausrichtung und die Berichterstattung an die Gesch\u00e4ftsleitung. Nimm Kontakt auf, dann besprechen wir, wo genau eure Organisation anfangen sollte.  <\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong><a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/meetings-eu1.hubspot.com\/mika-hakkarainen\">Buche einen Termin in meinem Kalender!<\/a><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d02490 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d02490\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b39bf0\" data-id=\"2b39bf0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be7f18e elementor-widget elementor-widget-text-editor\" data-id=\"be7f18e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<blockquote><p><em>Als vertrauensw\u00fcrdiger Berater deiner IT-Verwaltung ist es unsere Aufgabe sicherzustellen, dass die von dir verwaltete IT-Umgebung sicher bleibt und nicht gef\u00e4hrdet wird. Gemeinsam durch Lernen und Handeln wird deine Organisation erfolgreich sein. <\/em><\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Im Herbst wird ein einst\u00fcndiges Video angeschaut, die Teilnahme abgehakt und f\u00fcr das Audit vermerkt, dass das Personal geschult wurde. Im M\u00e4rz klickt jemand. Das Problem liegt nicht bei den Menschen, sondern in der Struktur der Schulung. So baust du ein Schulungsprogramm auf, dessen Ergebnis du in Zahlen zeigen kannst.   <\/p>\n","protected":false},"author":2,"featured_media":13163,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","inline_featured_image":false,"footnotes":""},"categories":[222,224,240],"tags":[223,527,528],"class_list":["post-13155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-it-sicherheit","category-microsoft-365","category-technologien","tag-it-sicherheit","tag-schulung","tag-simulationen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eine einmal j\u00e4hrlich durchgef\u00fchrte Sicherheitsschulung reicht nicht aus | Above IT Oy<\/title>\n<meta name=\"description\" content=\"Eine einmalige Sicherheitsschulung misst Anwesenheit, nicht Kompetenz. So baust du ein messbares Programm mit Phishing-Simulationen und nach NIS2-Anforderungen auf.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eine einmal j\u00e4hrlich durchgef\u00fchrte Sicherheitsschulung reicht nicht aus | Above IT Oy\" \/>\n<meta property=\"og:description\" content=\"Eine einmalige Sicherheitsschulung misst Anwesenheit, nicht Kompetenz. So baust du ein messbares Programm mit Phishing-Simulationen und nach NIS2-Anforderungen auf.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/\" \/>\n<meta property=\"og:site_name\" content=\"Above IT Oy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aboveitfi\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T09:04:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T10:40:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aboveit.fi\/wp-content\/uploads\/2026\/08\/AboveIT-12-e1787917212366.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"893\" \/>\n\t<meta property=\"og:image:height\" content=\"643\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mika Hakkarainen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mika Hakkarainen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/das-verwaltungsmodell-halt-azure-im-griff\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/das-verwaltungsmodell-halt-azure-im-griff\\\/\"},\"author\":{\"name\":\"Mika Hakkarainen\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#\\\/schema\\\/person\\\/042286daab0cbba998398a365b01589d\"},\"headline\":\"Eine einmal j\u00e4hrlich durchgef\u00fchrte Sicherheitsschulung reicht nicht aus\",\"datePublished\":\"2026-09-01T09:04:06+00:00\",\"dateModified\":\"2026-09-01T10:40:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/das-verwaltungsmodell-halt-azure-im-griff\\\/\"},\"wordCount\":1088,\"publisher\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/das-verwaltungsmodell-halt-azure-im-griff\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aboveit.fi\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/AboveIT-12-e1787917212366.jpg\",\"keywords\":[\"IT-Sicherheit\",\"schulung\",\"simulationen\"],\"articleSection\":[\"IT-Sicherheit\",\"Microsoft 365\",\"Technologien\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/das-verwaltungsmodell-halt-azure-im-griff\\\/\",\"url\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/das-verwaltungsmodell-halt-azure-im-griff\\\/\",\"name\":\"Eine einmal j\u00e4hrlich durchgef\u00fchrte Sicherheitsschulung reicht nicht aus | Above IT Oy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/das-verwaltungsmodell-halt-azure-im-griff\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/das-verwaltungsmodell-halt-azure-im-griff\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aboveit.fi\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/AboveIT-12-e1787917212366.jpg\",\"datePublished\":\"2026-09-01T09:04:06+00:00\",\"dateModified\":\"2026-09-01T10:40:45+00:00\",\"description\":\"Eine einmalige Sicherheitsschulung misst Anwesenheit, nicht Kompetenz. So baust du ein messbares Programm mit Phishing-Simulationen und nach NIS2-Anforderungen auf.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/das-verwaltungsmodell-halt-azure-im-griff\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aboveit.fi\\\/de\\\/das-verwaltungsmodell-halt-azure-im-griff\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/das-verwaltungsmodell-halt-azure-im-griff\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aboveit.fi\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/AboveIT-12-e1787917212366.jpg\",\"contentUrl\":\"https:\\\/\\\/aboveit.fi\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/AboveIT-12-e1787917212366.jpg\",\"width\":893,\"height\":643,\"caption\":\"Die Sicherheitsschulung des Personals h\u00e4lt das Personal wachsam\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/das-verwaltungsmodell-halt-azure-im-griff\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/ihr-ressourcenpartner-fuer-die-it-verwaltung\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eine einmal j\u00e4hrlich durchgef\u00fchrte Sicherheitsschulung reicht nicht aus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/\",\"name\":\"We Are Above IT\",\"description\":\"Tietohallinnon voimavarakumppani\",\"publisher\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#organization\",\"name\":\"Above IT Oy\",\"url\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aboveit.fi\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/aboveIT-logo.png\",\"contentUrl\":\"https:\\\/\\\/aboveit.fi\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/aboveIT-logo.png\",\"width\":1613,\"height\":383,\"caption\":\"Above IT Oy\"},\"image\":{\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aboveitfi\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aboveitfi\",\"https:\\\/\\\/instagram.com\\\/aboveitfi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/#\\\/schema\\\/person\\\/042286daab0cbba998398a365b01589d\",\"name\":\"Mika Hakkarainen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a524f3c964200b71dc33386439da51c4b3f74947e2015c221f4c90e36fec5096?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a524f3c964200b71dc33386439da51c4b3f74947e2015c221f4c90e36fec5096?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a524f3c964200b71dc33386439da51c4b3f74947e2015c221f4c90e36fec5096?s=96&d=mm&r=g\",\"caption\":\"Mika Hakkarainen\"},\"sameAs\":[\"https:\\\/\\\/aboveit.fi\"],\"url\":\"https:\\\/\\\/aboveit.fi\\\/de\\\/author\\\/mika-hakkarainenaboveit-fi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eine einmal j\u00e4hrlich durchgef\u00fchrte Sicherheitsschulung reicht nicht aus | Above IT Oy","description":"Eine einmalige Sicherheitsschulung misst Anwesenheit, nicht Kompetenz. So baust du ein messbares Programm mit Phishing-Simulationen und nach NIS2-Anforderungen auf.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/","og_locale":"de_DE","og_type":"article","og_title":"Eine einmal j\u00e4hrlich durchgef\u00fchrte Sicherheitsschulung reicht nicht aus | Above IT Oy","og_description":"Eine einmalige Sicherheitsschulung misst Anwesenheit, nicht Kompetenz. So baust du ein messbares Programm mit Phishing-Simulationen und nach NIS2-Anforderungen auf.","og_url":"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/","og_site_name":"Above IT Oy","article_publisher":"https:\/\/www.facebook.com\/aboveitfi","article_published_time":"2026-09-01T09:04:06+00:00","article_modified_time":"2026-09-01T10:40:45+00:00","og_image":[{"width":893,"height":643,"url":"https:\/\/aboveit.fi\/wp-content\/uploads\/2026\/08\/AboveIT-12-e1787917212366.jpg","type":"image\/jpeg"}],"author":"Mika Hakkarainen","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Mika Hakkarainen","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/#article","isPartOf":{"@id":"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/"},"author":{"name":"Mika Hakkarainen","@id":"https:\/\/aboveit.fi\/de\/#\/schema\/person\/042286daab0cbba998398a365b01589d"},"headline":"Eine einmal j\u00e4hrlich durchgef\u00fchrte Sicherheitsschulung reicht nicht aus","datePublished":"2026-09-01T09:04:06+00:00","dateModified":"2026-09-01T10:40:45+00:00","mainEntityOfPage":{"@id":"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/"},"wordCount":1088,"publisher":{"@id":"https:\/\/aboveit.fi\/de\/#organization"},"image":{"@id":"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/#primaryimage"},"thumbnailUrl":"https:\/\/aboveit.fi\/wp-content\/uploads\/2026\/08\/AboveIT-12-e1787917212366.jpg","keywords":["IT-Sicherheit","schulung","simulationen"],"articleSection":["IT-Sicherheit","Microsoft 365","Technologien"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/","url":"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/","name":"Eine einmal j\u00e4hrlich durchgef\u00fchrte Sicherheitsschulung reicht nicht aus | Above IT Oy","isPartOf":{"@id":"https:\/\/aboveit.fi\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/#primaryimage"},"image":{"@id":"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/#primaryimage"},"thumbnailUrl":"https:\/\/aboveit.fi\/wp-content\/uploads\/2026\/08\/AboveIT-12-e1787917212366.jpg","datePublished":"2026-09-01T09:04:06+00:00","dateModified":"2026-09-01T10:40:45+00:00","description":"Eine einmalige Sicherheitsschulung misst Anwesenheit, nicht Kompetenz. So baust du ein messbares Programm mit Phishing-Simulationen und nach NIS2-Anforderungen auf.","breadcrumb":{"@id":"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/#primaryimage","url":"https:\/\/aboveit.fi\/wp-content\/uploads\/2026\/08\/AboveIT-12-e1787917212366.jpg","contentUrl":"https:\/\/aboveit.fi\/wp-content\/uploads\/2026\/08\/AboveIT-12-e1787917212366.jpg","width":893,"height":643,"caption":"Die Sicherheitsschulung des Personals h\u00e4lt das Personal wachsam"},{"@type":"BreadcrumbList","@id":"https:\/\/aboveit.fi\/de\/das-verwaltungsmodell-halt-azure-im-griff\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/aboveit.fi\/de\/ihr-ressourcenpartner-fuer-die-it-verwaltung\/"},{"@type":"ListItem","position":2,"name":"Eine einmal j\u00e4hrlich durchgef\u00fchrte Sicherheitsschulung reicht nicht aus"}]},{"@type":"WebSite","@id":"https:\/\/aboveit.fi\/de\/#website","url":"https:\/\/aboveit.fi\/de\/","name":"We Are Above IT","description":"Tietohallinnon voimavarakumppani","publisher":{"@id":"https:\/\/aboveit.fi\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aboveit.fi\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aboveit.fi\/de\/#organization","name":"Above IT Oy","url":"https:\/\/aboveit.fi\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aboveit.fi\/de\/#\/schema\/logo\/image\/","url":"https:\/\/aboveit.fi\/wp-content\/uploads\/2024\/10\/aboveIT-logo.png","contentUrl":"https:\/\/aboveit.fi\/wp-content\/uploads\/2024\/10\/aboveIT-logo.png","width":1613,"height":383,"caption":"Above IT Oy"},"image":{"@id":"https:\/\/aboveit.fi\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aboveitfi","https:\/\/www.linkedin.com\/company\/aboveitfi","https:\/\/instagram.com\/aboveitfi"]},{"@type":"Person","@id":"https:\/\/aboveit.fi\/de\/#\/schema\/person\/042286daab0cbba998398a365b01589d","name":"Mika Hakkarainen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a524f3c964200b71dc33386439da51c4b3f74947e2015c221f4c90e36fec5096?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a524f3c964200b71dc33386439da51c4b3f74947e2015c221f4c90e36fec5096?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a524f3c964200b71dc33386439da51c4b3f74947e2015c221f4c90e36fec5096?s=96&d=mm&r=g","caption":"Mika Hakkarainen"},"sameAs":["https:\/\/aboveit.fi"],"url":"https:\/\/aboveit.fi\/de\/author\/mika-hakkarainenaboveit-fi\/"}]}},"_links":{"self":[{"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/posts\/13155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/comments?post=13155"}],"version-history":[{"count":5,"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/posts\/13155\/revisions"}],"predecessor-version":[{"id":13244,"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/posts\/13155\/revisions\/13244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/media\/13163"}],"wp:attachment":[{"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/media?parent=13155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/categories?post=13155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aboveit.fi\/de\/wp-json\/wp\/v2\/tags?post=13155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}